{"id":52253,"date":"2026-02-10T13:22:45","date_gmt":"2026-02-10T18:22:45","guid":{"rendered":"https:\/\/www.unemi.edu.ec\/?p=52253"},"modified":"2026-02-10T13:23:58","modified_gmt":"2026-02-10T18:23:58","slug":"unemi-conmemora-25-anos-de-historia-identidad-y-vision-de-futuro-en-una-emotiva-sesion-solemne","status":"publish","type":"post","link":"https:\/\/www.unemi.edu.ec\/index.php\/2026\/02\/10\/unemi-conmemora-25-anos-de-historia-identidad-y-vision-de-futuro-en-una-emotiva-sesion-solemne\/","title":{"rendered":"UNEMI conmemora 25 a\u00f1os de historia, identidad y visi\u00f3n de futuro en una emotiva sesi\u00f3n solemne"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La Universidad Estatal de Milagro (UNEMI) vivi\u00f3 una noche cargada de simbolismo, memoria y proyecci\u00f3n durante la sesi\u00f3n solemne por la conmemoraci\u00f3n de su Vig\u00e9simo Quinto Aniversario, un acto que reuni\u00f3 a autoridades nacionales y universitarias, invitados especiales y a la comunidad acad\u00e9mica, para rendir homenaje a una historia construida con esfuerzo colectivo, compromiso p\u00fablico y vocaci\u00f3n educativa.<\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\" wp-image-52259 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631629327_1369984801840210_8657988868418340682_n-300x200.jpg\" alt=\"\" width=\"462\" height=\"308\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631629327_1369984801840210_8657988868418340682_n-300x200.jpg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631629327_1369984801840210_8657988868418340682_n-1024x683.jpg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631629327_1369984801840210_8657988868418340682_n-768x512.jpg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631629327_1369984801840210_8657988868418340682_n.jpg 1440w\" sizes=\"(max-width: 462px) 100vw, 462px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La ceremonia se desarroll\u00f3 en un ambiente solemne y emotivo, iniciando con un video introductorio acompa\u00f1ado de un show de luces que dio paso a la bienvenida oficial, marcando el inicio de una jornada que record\u00f3 el origen, el crecimiento y el impacto de la UNEMI en el desarrollo del pa\u00eds. El ingreso del \u00d3rgano Colegiado Superior y de las autoridades invitadas simboliz\u00f3 el respaldo institucional y nacional a una universidad que ha sabido consolidarse dentro del sistema de educaci\u00f3n superior ecuatoriano.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante la apertura del acto, la vicerrectora Acad\u00e9mica de Formaci\u00f3n de Grado, Dra. Jesennia C\u00e1rdenas Cobo<\/span><b>,<\/b><span style=\"font-weight: 400;\"> destac\u00f3 el esp\u00edritu que ha guiado a la instituci\u00f3n desde sus inicios: <\/span><i><span style=\"font-weight: 400;\">\u201cSomos una comunidad universitaria que crey\u00f3 y sigue creyendo que la educaci\u00f3n es la fuerza m\u00e1s poderosa de cambio. Esa convicci\u00f3n, presente desde nuestras ra\u00edces, constituye el ADN que nos permite crecer sin perder nuestra esencia\u201d<\/span><\/i><span style=\"font-weight: 400;\">, se\u00f1al\u00f3.<\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\" wp-image-52255 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631053292_1369984785173545_6138491062517513177_n-300x200.jpg\" alt=\"\" width=\"464\" height=\"310\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631053292_1369984785173545_6138491062517513177_n-300x200.jpg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631053292_1369984785173545_6138491062517513177_n-1024x684.jpg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631053292_1369984785173545_6138491062517513177_n-768x513.jpg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631053292_1369984785173545_6138491062517513177_n.jpg 1440w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">A lo largo de la jornada, autoridades acad\u00e9micas y representantes de organismos nacionales resaltaron el rol de la UNEMI como una universidad p\u00fablica comprometida con la calidad acad\u00e9mica, la investigaci\u00f3n, la vinculaci\u00f3n con la sociedad y la formaci\u00f3n integral de nuevas generaciones. Las intervenciones especiales reafirmaron la importancia de una educaci\u00f3n superior articulada al desarrollo humano, social y productivo del pa\u00eds.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este contexto, la Dra. Carmita \u00c1lvarez Santana, consejera acad\u00e9mica del Consejo de Educaci\u00f3n Superior del Ecuador, subray\u00f3 el impacto social de la instituci\u00f3n: <\/span><i><span style=\"font-weight: 400;\">\u201cLa UNEMI ha sido arquitecta del destino de miles de personas. Ha sido la gran puerta abierta para que j\u00f3venes contin\u00faen sus estudios y vean sus sue\u00f1os realizados. Aqu\u00ed la oportunidad no es un concepto abstracto: es un t\u00edtulo profesional, es la primera generaci\u00f3n de muchas familias que accede a la educaci\u00f3n superior, es el ascenso social hecho realidad\u201d<\/span><\/i><span style=\"font-weight: 400;\">, indic\u00f3.<\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\" wp-image-52256 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631997006_1369984835173540_106873293108359570_n-300x200.jpg\" alt=\"\" width=\"452\" height=\"302\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631997006_1369984835173540_106873293108359570_n-300x200.jpg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631997006_1369984835173540_106873293108359570_n-1024x684.jpg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631997006_1369984835173540_106873293108359570_n-768x513.jpg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/631997006_1369984835173540_106873293108359570_n.jpg 1440w\" sizes=\"(max-width: 452px) 100vw, 452px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La sesi\u00f3n solemne incluy\u00f3 un espacio de reconocimientos institucionales, en el que se rindi\u00f3 homenaje a servidores y autoridades cuya trayectoria, compromiso y vocaci\u00f3n de servicio han contribuido de manera significativa al crecimiento de la universidad. Estos reconocimientos evidenciaron que la historia de la UNEMI se construye a partir del trabajo diario de personas que creen en la educaci\u00f3n como motor de transformaci\u00f3n social.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por su parte, la ministra de Desarrollo Humano, Mgtr. Zaida Rovira Jurado, resalt\u00f3 la importancia del acceso a la educaci\u00f3n superior como pol\u00edtica p\u00fablica y valor\u00f3 el impacto de la UNEMI en la regi\u00f3n: <\/span><i><span style=\"font-weight: 400;\">\u201cCompartir con ustedes esta noche es de vital importancia, porque nos permite verificar que nuestros j\u00f3venes, hombres y mujeres, tengan oportunidades reales de acceso a la educaci\u00f3n superior. La UNEMI, con m\u00e1s de 70.000 estudiantes, ha sido un aporte fundamental para la formaci\u00f3n de nuestros j\u00f3venes y para brindar oportunidades que muchos no pudieron encontrar en otros espacios\u201d<\/span><\/i><span style=\"font-weight: 400;\">, expres\u00f3.<\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\" wp-image-52257 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630889059_1369984775173546_561085498474208978_n-300x200.jpg\" alt=\"\" width=\"464\" height=\"309\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630889059_1369984775173546_561085498474208978_n-300x200.jpg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630889059_1369984775173546_561085498474208978_n-1024x684.jpg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630889059_1369984775173546_561085498474208978_n-768x513.jpg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630889059_1369984775173546_561085498474208978_n.jpg 1440w\" sizes=\"(max-width: 464px) 100vw, 464px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Uno de los momentos m\u00e1s inspiradores de la noche fue la proyecci\u00f3n del video futurista<\/span><b>,<\/b><span style=\"font-weight: 400;\"> que permiti\u00f3 visualizar la visi\u00f3n institucional de la UNEMI hacia los pr\u00f3ximos a\u00f1os, reafirmando su apuesta por la innovaci\u00f3n, la planificaci\u00f3n estrat\u00e9gica y el desarrollo sostenible. Este mensaje de futuro se consolid\u00f3 con la intervenci\u00f3n del rector, Ph. D. Fabricio Guevara Viej\u00f3<\/span><b>,<\/b><span style=\"font-weight: 400;\"> quien destac\u00f3 que los 25 a\u00f1os representan una etapa de madurez institucional y, al mismo tiempo, un punto de partida hacia nuevos desaf\u00edos y responsabilidades con el pa\u00eds.<\/span><\/p>\n<p><i><span style=\"font-weight: 400;\">\u201cTen\u00edamos el firme compromiso de transformar la educaci\u00f3n superior, de no dar la espalda a las necesidades de los j\u00f3venes y de convertir el problema del acceso en una oportunidad. Hoy somos la universidad p\u00fablica m\u00e1s grande del pa\u00eds, con m\u00e1s de 70.000 estudiantes de pregrado y cerca de 30.000 en posgrado\u201d<\/span><\/i><span style=\"font-weight: 400;\">, se\u00f1al\u00f3 la m\u00e1xima autoridad. Asimismo, hizo un llamado a creer en la formaci\u00f3n profesional como herramienta de progreso: <\/span><i><span style=\"font-weight: 400;\">\u201cCuando estamos preparados, formados y tenemos la actitud correcta, las oportunidades no solo aparecen, tambi\u00e9n se crean\u201d<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\" wp-image-52258 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630443138_1369984831840207_2161013605322235982_n-300x200.jpg\" alt=\"\" width=\"498\" height=\"332\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630443138_1369984831840207_2161013605322235982_n-300x200.jpg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630443138_1369984831840207_2161013605322235982_n-1024x684.jpg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630443138_1369984831840207_2161013605322235982_n-768x513.jpg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2026\/02\/630443138_1369984831840207_2161013605322235982_n.jpg 1440w\" sizes=\"(max-width: 498px) 100vw, 498px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">La conmemoraci\u00f3n de los 25 a\u00f1os de la Universidad Estatal de Milagro celebr\u00f3 el tiempo transcurrido y ratific\u00f3 una identidad construida con visi\u00f3n, trabajo y compromiso social. Una universidad que honra su historia, valora a su gente y proyecta su futuro con responsabilidad y esperanza.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Estatal de Milagro (UNEMI) vivi\u00f3 una noche cargada de simbolismo, memoria y proyecci\u00f3n durante la sesi\u00f3n solemne por la conmemoraci\u00f3n de su Vig\u00e9simo Quinto Aniversario, un acto que [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":52254,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[54],"tags":[],"class_list":["post-52253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/52253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/comments?post=52253"}],"version-history":[{"count":1,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/52253\/revisions"}],"predecessor-version":[{"id":52260,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/52253\/revisions\/52260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/media\/52254"}],"wp:attachment":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/media?parent=52253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/categories?post=52253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/tags?post=52253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}