{"id":43113,"date":"2024-08-01T19:15:41","date_gmt":"2024-08-02T00:15:41","guid":{"rendered":"https:\/\/www.unemi.edu.ec\/?p=43113"},"modified":"2024-08-01T19:15:41","modified_gmt":"2024-08-02T00:15:41","slug":"con-mas-de-200-medallas-unemi-se-consolida-en-el-taekwondo-universitario","status":"publish","type":"post","link":"https:\/\/www.unemi.edu.ec\/index.php\/2024\/08\/01\/con-mas-de-200-medallas-unemi-se-consolida-en-el-taekwondo-universitario\/","title":{"rendered":"Con m\u00e1s de 200 medallas, UNEMI se consolida en el Taekwondo universitario"},"content":{"rendered":"<p><span style=\"font-size: 14pt;\">En los \u00faltimos a\u00f1os, la selecci\u00f3n de Taewkondo de la Universidad Estatal de Milagro (UNEMI) se ha destacado en importantes torneos locales y nacionales.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El entrenador a cargo de la selecci\u00f3n, Daniel Manso, tiene dos a\u00f1os instruyendo a los estudiantes con las mejores t\u00e9cnicas, contabilizando un total de 210 medallas para UNEMI, en diferentes torneos.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El buen nivel de los seleccionados se vio reflejado una vez m\u00e1s, durante el \u201c5to Open Nobol\u201d, torneo jugado en julio pasado. El equipo obtuvo el segundo lugar en poomsae y el cuarto lugar en combate.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Manso se\u00f1ala que todas las participaciones son relevantes y ayudan en el desempe\u00f1o de los j\u00f3venes.<em> \u201cEstamos en conversaciones con varias Instituciones de Educaci\u00f3n Superior que tienen grupos de taekwondo para organizar pr\u00e1cticas, pero nuestra competencia fundamental es el campeonato interuniversitario internacional y militar en Guayaquil, que se llevar\u00e1 a cabo en octubre de este a\u00f1o\u201d<\/em>, indica el entrenador.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">En el primer periodo acad\u00e9mico del 2024, 45 alumnos formaron parte de la selecci\u00f3n de Taekwondo. Los estudiantes entrenan arduamente para conseguir m\u00e1s triunfos que destaquen la labor y el esfuerzo realizado por los j\u00f3venes.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El estratega expresa su agradecimiento por la oportunidad de poder impartir esta disciplina. <em>\u201cGracias al director del Centro para la Formaci\u00f3n y Promoci\u00f3n del Deporte Universitario, Mgtr. Christian Velasco, y a la vicerrectora de Vinculaci\u00f3n, Dra. Mayra D\u00b4Armas, por haber confiado en mi trabajo y espero poder seguir impartiendo mis conocimientos, que he venido desarrollando desde hace quince a\u00f1os\u201d. <\/em><\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Ronald Idrovo, de 20 a\u00f1os, cursa el segundo semestre de la carrera de Enfermer\u00eda y es seleccionado de Taekwondo desde hace un a\u00f1o y cinco meses. El joven califica su experiencia practicando este deporte.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201c<em>Durante este tiempo he recopilado muchos recuerdos, tambi\u00e9n he hecho amistades que han dejado ense\u00f1anzas y aprendizajes. \u00a0He podido conocer a quien ahora es mi maestro, me he maravillado con sus historias y ense\u00f1anzas, espero poder seguir en la selecci\u00f3n\u201d,<\/em> expresa Ronald.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">El seleccionado indica que praticar un arte marcial es algo que hab\u00eda deseado toda la vida. Cuando se enter\u00f3 que en la Instituci\u00f3n se impart\u00eda este deporte, fue directamente a inscribirse.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">Adem\u00e1s, menciona que, por su carrera (Enfermer\u00eda), se torna un poco complejo ir a entrenar en los d\u00edas designados, sin embargo, la disciplina y las ganas de mejorar en este deporte han logrado que consiga un balance y as\u00ed disfrutar del proceso y las victorias alcanzadas.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\"><em>\u201cAgradezco a la universidad por permitir que estudiantes como yo puedan tener la facilidad de ser parte del mundo de las artes marciales, como lo es el taekwondo y encaminarme hacia una nueva pasi\u00f3n, metas, esfuerzo y el compromiso que conlleva este deporte\u201d, <\/em>se\u00f1ala el seleccionado.<\/span><\/p>\n<p><span style=\"font-size: 14pt;\">\u201c<em>Los seleccionados de taekwondo siempre dejan en alto el nombre de la Instituci\u00f3n y esperamos obtener m\u00e1s t\u00edtulos, para as\u00ed llegar a ser la universidad con m\u00e1s campeones en el pa\u00eds\u201d, opin\u00f3 Velasco. (OG)<\/em><\/span><\/p>\n<p><img loading="lazy" decoding="async" decoding=\"async\" class=\"wp-image-43116 aligncenter\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-01-at-6.59.46-PM-300x197.jpeg\" alt=\"\" width=\"696\" height=\"457\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-01-at-6.59.46-PM-300x197.jpeg 300w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-01-at-6.59.46-PM-1024x672.jpeg 1024w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-01-at-6.59.46-PM-768x504.jpeg 768w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-01-at-6.59.46-PM.jpeg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><strong><span style=\"font-size: 14pt;\">Participaciones:<\/span><\/strong><\/p>\n<ul>\n<li><span style=\"font-size: 14pt;\">Primer Campeonato Nacional Inter Universitario y Polit\u00e9cnico \u201cUTA 2022 (octavo lugar).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Tercer campeonato Inter-Provincial \u201cCopa Universal\u201d CUMAND\u00c1 (primer lugar en Poomsae y tercer lugar en kyorugi).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">VI Internacional Open Salinas 2022 (cuarto lugar).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Tercer campeonato \u201cCopa de campeones FTKD 2023\u201d (segundo lugar en Poomsae).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Cuarto Open Nobol 2023 (tercer lugar en y combate).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">Segundo Open Nacional Universitario UTA (tercer lugar).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">1er Tope t\u00e9cnico contra la UPSE.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">COPA CLUB SPORT EMELEC 2024 (Segundo lugar en Poomsae).<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">1er Tope interuniversitario contra la Escuela de Grumetes Salinas 2024.<\/span><\/li>\n<li><span style=\"font-size: 14pt;\">5to Open Nobol 2024 (segundo lugar en poomsae y el cuarto lugar en combate).<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En los \u00faltimos a\u00f1os, la selecci\u00f3n de Taewkondo de la Universidad Estatal de Milagro (UNEMI) se ha destacado en importantes torneos locales y nacionales. El entrenador a cargo de la [&hellip;]<\/p>\n","protected":false},"author":34,"featured_media":43115,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[345,54],"tags":[],"class_list":["post-43113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/43113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/comments?post=43113"}],"version-history":[{"count":1,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/43113\/revisions"}],"predecessor-version":[{"id":43117,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/43113\/revisions\/43117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/media\/43115"}],"wp:attachment":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/media?parent=43113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/categories?post=43113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/tags?post=43113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}