{"id":4247,"date":"2015-12-14T16:29:51","date_gmt":"2015-12-14T16:29:51","guid":{"rendered":"https:\/\/https:\/\/www.unemi.edu.ec\/\/wordpress\/?p=4247"},"modified":"2019-03-31T01:36:38","modified_gmt":"2019-03-31T01:36:38","slug":"proyecto-de-vinculacion-beneficia-a-370-estudiantes-de-bachillerato-en-canton-simon-bolivar","status":"publish","type":"post","link":"https:\/\/www.unemi.edu.ec\/index.php\/2015\/12\/14\/proyecto-de-vinculacion-beneficia-a-370-estudiantes-de-bachillerato-en-canton-simon-bolivar\/","title":{"rendered":"Proyecto de Vinculaci\u00f3n beneficia a 370 estudiantes de bachillerato en cant\u00f3n Sim\u00f3n Bol\u00edvar"},"content":{"rendered":"<p><img loading="lazy" decoding="async" decoding=\"async\" class=\"size-full wp-image-4248 alignleft\" src=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2018\/02\/Proyecto-de-Vinculaci\u00f3n-beneficia-a-370-estudiantes-de-bachillerato-en-cant\u00f3n-Sim\u00f3n-Bol\u00edvar.jpg\" alt=\"\" width=\"448\" height=\"297\" srcset=\"https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2018\/02\/Proyecto-de-Vinculaci\u00f3n-beneficia-a-370-estudiantes-de-bachillerato-en-cant\u00f3n-Sim\u00f3n-Bol\u00edvar.jpg 448w, https:\/\/www.unemi.edu.ec\/wp-content\/uploads\/2018\/02\/Proyecto-de-Vinculaci\u00f3n-beneficia-a-370-estudiantes-de-bachillerato-en-cant\u00f3n-Sim\u00f3n-Bol\u00edvar-300x199.jpg 300w\" sizes=\"(max-width: 448px) 100vw, 448px\" \/>Estudiantes de tercer semestre de la carrera de Licenciatura en Enfermer\u00eda de la Facultad de Ciencias de la Salud (FACS) de UNEMI, desarrollaron en la Unidad Educativa Antonio Parra Velasco, el proyecto de Vinculaci\u00f3n con la Colectividad, denominado Prevenci\u00f3n del consumo de drogas il\u00edcitas en adolescentes, con el objetivo de llevar un mensaje informativo y de prevenci\u00f3n a los j\u00f3venes.<\/p>\n<p>370 estudiantes de bachillerato resultaron beneficiados con este proyecto, al recibir charlas informativas por parte de nuestros futuros profesionales de Enfermer\u00eda. El desarrollo de actividades deportivas, la presentaci\u00f3n de un mural y una casa abierta, formaron parte del d\u00eda.<\/p>\n<p>La estudiante de UNEMI Mar\u00eda Jos\u00e9 Zambrano, comenta que se incentiv\u00f3 a los bachilleres, mediante la participaci\u00f3n activa en la realizaci\u00f3n de un mural con el tema \u201cmanos sin drogas\u201d, y adem\u00e1s d\u00e1ndoles protagonismo en la casa abierta.<\/p>\n<p>\u201cHemos capacitado a los chicos y son los encargados de exponer en la casa abierta, procuramos que conozcan el tema para que sean ellos quienes transmitan el mensaje de prevenci\u00f3n a sus compa\u00f1eros\u201d coment\u00f3 Zambrano.<\/p>\n<p>Shirley Le\u00f3n de 16 a\u00f1os, estudiante de primer a\u00f1o de bachillerato, fue una de las encargadas de exponer el tema en uno de los stands.<\/p>\n<p>\u201cLos estudiantes de UNEMI nos capacitaron sobre un tema muy importante como son las drogas, el alcohol y sus consecuencias; nosotros como adolescentes debemos aprender de esto, las drogas no son un camino a seguir y puede traernos muchas consecuencias, incluso la muerte\u201d dijo Shirley.<\/p>\n<p>Julio Posligua, docente de la FACS y l\u00edder de este proyecto se dirigi\u00f3 a los j\u00f3venes para agradecer su apertura y participaci\u00f3n activa.<\/p>\n<p>\u201cEl objetivo de este trabajo es que ustedes, j\u00f3venes, que son la poblaci\u00f3n de riesgo, se nutran cient\u00edficamente con el aporte de nuestros estudiantes y las actividades realizadas; agradecemos su presencia e inter\u00e9s para que estas actividades se desarrollen en su beneficio\u201d finaliz\u00f3 el docente.<\/p>\n<p>La ma\u00f1ana se desarroll\u00f3 entre actividades art\u00edsticas a cargo del grupo de danzas UNEMI y estudiantes de la FACS y culmin\u00f3 con encuentros deportivos entre los estudiantes de bachillerato.         <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudiantes de tercer semestre de la carrera de Licenciatura en Enfermer\u00eda de la Facultad de Ciencias de la Salud (FACS) de UNEMI, desarrollaron en la Unidad Educativa Antonio Parra Velasco, [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_joinchat":[],"footnotes":""},"categories":[54],"tags":[],"class_list":["post-4247","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/4247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/comments?post=4247"}],"version-history":[{"count":0,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/posts\/4247\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/media?parent=4247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/categories?post=4247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unemi.edu.ec\/index.php\/wp-json\/wp\/v2\/tags?post=4247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}